{"id":1851,"date":"2018-03-03T12:00:38","date_gmt":"2018-03-03T12:00:38","guid":{"rendered":"https:\/\/www.maj.aventure-pyreneenne.com\/?p=1851"},"modified":"2020-01-27T17:46:29","modified_gmt":"2020-01-27T17:46:29","slug":"formigueres-station-ski-pyrenees-orientales","status":"publish","type":"post","link":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/","title":{"rendered":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1851\" class=\"elementor elementor-1851\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17e603d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17e603d\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;af167ca&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;50&quot;,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:&quot;50&quot;,&quot;jet_parallax_layout_bg_y&quot;:&quot;50&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef8e15d\" data-id=\"ef8e15d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3a49f8 elementor-widget elementor-widget-text-editor\" data-id=\"e3a49f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Focus sur une station de ski devenue incontournable en Pyr\u00e9n\u00e9es Orientales : Formigu\u00e8res. On fait le point pour vous sur le domaine skiable, les services et bien s\u00fbr les itin\u00e9raires en ski de randonn\u00e9e. <\/em><\/p><h2><span style=\"font-size: 0.725em;\">UNE STATION DE SKI EN PLEINE NATURE<\/span><\/h2><p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-1854 size-full\" src=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/station-ski-formigueres.jpg\" alt=\"Sation de ski de Formigu\u00e8res\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/station-ski-formigueres.jpg 1000w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/station-ski-formigueres-300x200.jpg 300w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/station-ski-formigueres-768x511.jpg 768w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/station-ski-formigueres-600x400.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>Formigu\u00e8res est une station de ski nature \u00e0 taille humaine. Le domaine skiable compte<strong> 25 km<\/strong>, soit <strong>19 pistes de ski alpin<\/strong>, et <strong>180 hectares s\u00e9curis\u00e9s<\/strong> pour les amateurs de descentes hors-pistes entre les arbres. Le front de neige accueille un espace d\u00e9butant et des remont\u00e9es m\u00e9caniques adapt\u00e9es \u00e0 l\u2019apprentissage du ski.<\/p><h2 style=\"text-align: justify;\"><span style=\"font-size: 0.725em;\">APPRENEZ \u00c0 SKIER<\/span><\/h2><p style=\"text-align: justify;\"><a href=\"https:\/\/www.esf-formigueres.com\/\" target=\"_blank\" rel=\"noopener\">L\u2019\u00e9cole de ski de Formigu\u00e8res<\/a> accueille les enfants au jardin des neiges et d\u00e8s le plus jeune \u00e2ge dans le cadre chaleureux du club Piou-Piou. Tous les moniteurs sont dipl\u00f4m\u00e9s et bilingues, ils sont aptes \u00e0 fournir le mat\u00e9riel et l\u2019encadrement n\u00e9cessaire \u00e0 la pratique de l\u2019Handiski.<\/p><h2 style=\"text-align: left;\"><span style=\"font-size: 0.725em;\">MANGEZ LES PIEDS DANS LA NEIGE<\/span><\/h2><p style=\"text-align: justify;\">Pour se restaurer, la station dispose en bas des pistes, d\u2019un restaurant La Calmazeille, d\u2019un espace snack et d\u2019une salle Hors sac. Un espace de d\u00e9tente vous y attend. Des aires de pique-nique sont \u00e9galement am\u00e9nag\u00e9es pour profiter d\u2019un moment convivial en famille.<\/p><p style=\"text-align: left;\"><strong><img decoding=\"async\" class=\"size-medium wp-image-1856 alignleft\" src=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/snowlicious-food-truck-formigu\u00e8res-560x373-300x200.jpg\" alt=\"Snowlicious station de Formigu\u00e8res\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/snowlicious-food-truck-formigu\u00e8res-560x373-300x200.jpg 300w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/snowlicious-food-truck-formigu\u00e8res-560x373.jpg 560w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>La snowlicious : un food truck version dameuse !<\/strong><\/p><p style=\"text-align: justify;\">D\u00e9guster un chocolat chaud \u00e0 2000 m au milieu du domaine skiable, c&rsquo;est vraiment sympa. Mais prendre sa commande sur une dameuse, c&rsquo;est g\u00e9nial ! Vous l&rsquo;avez compris, la Snowlicious est une dameuse reconvertie en Food Truck. Dimitri et Chlo\u00e9 vous proposent de la restauration rapide concoct\u00e9e avec des produits locaux, un super accueil et un cadre \u00e0 couper le souffle.<span style=\"font-size: 0.725em;\"><br \/><\/span><\/p><h2 style=\"text-align: justify;\"><span style=\"font-size: 0.725em;\">UN SPOT DE SKI DE RANDONN\u00c9E INCONTOURNABLE<\/span><\/h2><p style=\"text-align: justify;\">Formigu\u00e8res est un secteur qui se pr\u00eate \u00e0 la pratique du ski de randonn\u00e9e. Les Camporells, Le pic Mortiers (2605 m), le pic P\u00e9ric (2810 m), la vall\u00e9e du Galbe sont autant d&rsquo;itin\u00e9raires incontournables en Pyr\u00e9n\u00e9es Orientales.<br \/>Face au d\u00e9veloppement de la pratique, la station a d\u00e9cid\u00e9 de mettre en place <a href=\"http:\/\/rando-ski-pyrenees.com\/decouverte\/notre-demarche\/\" target=\"_blank\" rel=\"noopener\">3 circuits de ski de randonn\u00e9e balis\u00e9s<\/a> sur le domaine skiable et une charte de bonne conduite. Si vous voulez acc\u00e9der plus rapidement aux espaces vierges, vous avez aussi la possibilit\u00e9 de prendre les 2 t\u00e9l\u00e9si\u00e8ges.<\/p><p style=\"text-align: justify;\">Pour ceux qui veulent s&rsquo;initier aux plaisirs du <a href=\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/alpinisme-hivernal-pyrenees-orientales\/\">ski de randonn\u00e9e et de l&rsquo;alpinisme<\/a> avec un professionnel, n&rsquo;h\u00e9sitez pas \u00e0 faire appel \u00e0 un des guides de Haute Montagne d&rsquo;Aventure Pyr\u00e9n\u00e9enne bien s\u00fbr !\u00a0<\/p><p style=\"text-align: justify;\"><em><img decoding=\"async\" class=\"wp-image-1852 size-full aligncenter\" src=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\" alt=\"Ski de randonn\u00e9e depuis la station de ski de Formigu\u00e8res - Les Camporells\" width=\"1920\" height=\"800\" srcset=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg 1920w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric-300x125.jpg 300w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric-768x320.jpg 768w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric-1024x427.jpg 1024w, https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric-600x250.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/em><\/p><h2 style=\"text-align: left;\"><span style=\"font-size: 0.725em;\">FORMIGU\u00c8RES &#8211; FICHE TECHNIQUE<\/span><\/h2><ul><li style=\"text-align: left;\">25 km de pistes &#8211; 19 pistes de ski alpin : 1 noire, 9 rouges, 6 bleues, 3 vertes<\/li><li style=\"text-align: left;\">180 hectares de domaine skiable freestyle s\u00e9curis\u00e9 entre les arbres<\/li><li style=\"text-align: left;\">Espace d\u00e9butant au pied des pistes<\/li><li style=\"text-align: left;\">1 snowpark, 1 boardercross, 1 espace freestyle, 1 piste \u00e0 bosses, woodpark<\/li><li style=\"text-align: left;\">2 t\u00e9l\u00e9si\u00e8ges de quatre places, 4 t\u00e9l\u00e9skis, 1 t\u00e9l\u00e9corde gratuite, 1 tapis roulant<\/li><li style=\"text-align: left;\">70 canons \u00e0 neige.<\/li><li style=\"text-align: left;\">Petits + : location de mat\u00e9riel en pied de pistes, ventes de forfaits directement sur Internet, sur automates ou aux guichets.<\/li><li style=\"text-align: left;\">3 Itin\u00e9raires ski de Randonn\u00e9e<\/li><li style=\"text-align: left;\">Altitude : 1 500m \/ 2 400 m<\/li><\/ul><h3 style=\"text-align: center;\"><span style=\"font-size: 0.725em;\">TOUT SAVOIR SUR LA STATION DE SKI DE FORMIGU\u00c8RES<\/span><\/h3><p><strong><span style=\"font-size: 1.175em;\">Station de Formigu\u00e8res<\/span><br \/><\/strong>T\u00e9l : 33 (0)4 68 04 43 75<br \/>Email : station@formigueres.fr<br \/><a href=\"http:\/\/www.formigueres.fr\/\" target=\"_blank\" rel=\"noopener\">www.formigueres.fr<\/a><\/p><p><span style=\"font-size: 1.175em;\"><strong>Office du tourisme de Formigu\u00e8res<\/strong><\/span><br \/>T\u00e9l : 33 (0)4 68 04 47 35<br \/>Email : <a href=\"mailto:tourisme@formigueres.fr\" target=\"_blank\" rel=\"noopener\">tourisme@formigueres.fr<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Focus sur une station de ski devenue incontournable en Pyr\u00e9n\u00e9es Orientales : Formigu\u00e8res. On fait le point pour vous sur le domaine skiable, les services et bien s\u00fbr les itin\u00e9raires en ski de randonn\u00e9e. UNE STATION DE SKI EN PLEINE NATURE Formigu\u00e8res est une station de ski nature \u00e0 taille humaine. Le domaine skiable compte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne\" \/>\n<meta property=\"og:description\" content=\"Focus sur une station de ski devenue incontournable en Pyr\u00e9n\u00e9es Orientales : Formigu\u00e8res. On fait le point pour vous sur le domaine skiable, les services et bien s\u00fbr les itin\u00e9raires en ski de randonn\u00e9e. UNE STATION DE SKI EN PLEINE NATURE Formigu\u00e8res est une station de ski nature \u00e0 taille humaine. Le domaine skiable compte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\" \/>\n<meta property=\"og:site_name\" content=\"Aventure Pyr\u00e9n\u00e9enne\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-03T12:00:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-27T17:46:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fabrice FONSAGRIVE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fabrice FONSAGRIVE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\"},\"author\":{\"name\":\"Fabrice FONSAGRIVE\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b\"},\"headline\":\"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales\",\"datePublished\":\"2018-03-03T12:00:38+00:00\",\"dateModified\":\"2020-01-27T17:46:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\"},\"wordCount\":565,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\",\"url\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\",\"name\":\"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne\",\"isPartOf\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\",\"datePublished\":\"2018-03-03T12:00:38+00:00\",\"dateModified\":\"2020-01-27T17:46:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage\",\"url\":\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\",\"contentUrl\":\"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg\",\"width\":1920,\"height\":800,\"caption\":\"Ski de randonn\u00e9e depuis la station de ski de Formigu\u00e8res - Les Camporells\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.maj.aventure-pyreneenne.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#website\",\"url\":\"https:\/\/www.maj.aventure-pyreneenne.com\/\",\"name\":\"Aventure Pyr\u00e9n\u00e9enne\",\"description\":\"#LiveYourAdventure\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.maj.aventure-pyreneenne.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b\",\"name\":\"Fabrice FONSAGRIVE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/88ae90e6243eec90cc024a02dbaef2802e5723ad309d9b6bfb73e7a45e8bb3d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/88ae90e6243eec90cc024a02dbaef2802e5723ad309d9b6bfb73e7a45e8bb3d0?s=96&d=mm&r=g\",\"caption\":\"Fabrice FONSAGRIVE\"},\"description\":\"Passionn\u00e9 de sports nature, je suis guide de canyoning et directeur de l'Agence Aventure Pyr\u00e9n\u00e9enne #LiveYourAdventure\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/fabrice-fonsagrive\/\"],\"url\":\"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/author\/fabrice\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne","og_description":"Focus sur une station de ski devenue incontournable en Pyr\u00e9n\u00e9es Orientales : Formigu\u00e8res. On fait le point pour vous sur le domaine skiable, les services et bien s\u00fbr les itin\u00e9raires en ski de randonn\u00e9e. UNE STATION DE SKI EN PLEINE NATURE Formigu\u00e8res est une station de ski nature \u00e0 taille humaine. Le domaine skiable compte [&hellip;]","og_url":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/","og_site_name":"Aventure Pyr\u00e9n\u00e9enne","article_published_time":"2018-03-03T12:00:38+00:00","article_modified_time":"2020-01-27T17:46:29+00:00","og_image":[{"width":1920,"height":800,"url":"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg","type":"image\/jpeg"}],"author":"Fabrice FONSAGRIVE","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Fabrice FONSAGRIVE","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#article","isPartOf":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/"},"author":{"name":"Fabrice FONSAGRIVE","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b"},"headline":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales","datePublished":"2018-03-03T12:00:38+00:00","dateModified":"2020-01-27T17:46:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/"},"wordCount":565,"commentCount":0,"image":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg","articleSection":["blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/","url":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/","name":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales - Aventure Pyr\u00e9n\u00e9enne","isPartOf":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage"},"image":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg","datePublished":"2018-03-03T12:00:38+00:00","dateModified":"2020-01-27T17:46:29+00:00","author":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b"},"breadcrumb":{"@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#primaryimage","url":"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg","contentUrl":"https:\/\/www.maj.aventure-pyreneenne.com\/wp-content\/uploads\/2020\/01\/ski-randonnee-camporells-peric.jpg","width":1920,"height":800,"caption":"Ski de randonn\u00e9e depuis la station de ski de Formigu\u00e8res - Les Camporells"},{"@type":"BreadcrumbList","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/2018\/03\/03\/formigueres-station-ski-pyrenees-orientales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.maj.aventure-pyreneenne.com\/"},{"@type":"ListItem","position":2,"name":"Formigu\u00e8res : une station de ski dans les Pyr\u00e9n\u00e9es Orientales"}]},{"@type":"WebSite","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#website","url":"https:\/\/www.maj.aventure-pyreneenne.com\/","name":"Aventure Pyr\u00e9n\u00e9enne","description":"#LiveYourAdventure","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.maj.aventure-pyreneenne.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/d8b54887142f1704536005e627293e9b","name":"Fabrice FONSAGRIVE","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.maj.aventure-pyreneenne.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/88ae90e6243eec90cc024a02dbaef2802e5723ad309d9b6bfb73e7a45e8bb3d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88ae90e6243eec90cc024a02dbaef2802e5723ad309d9b6bfb73e7a45e8bb3d0?s=96&d=mm&r=g","caption":"Fabrice FONSAGRIVE"},"description":"Passionn\u00e9 de sports nature, je suis guide de canyoning et directeur de l'Agence Aventure Pyr\u00e9n\u00e9enne #LiveYourAdventure","sameAs":["https:\/\/www.linkedin.com\/in\/fabrice-fonsagrive\/"],"url":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/author\/fabrice\/"}]}},"_links":{"self":[{"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/posts\/1851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/comments?post=1851"}],"version-history":[{"count":2,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/posts\/1851\/revisions"}],"predecessor-version":[{"id":1857,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/posts\/1851\/revisions\/1857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/media\/1852"}],"wp:attachment":[{"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/media?parent=1851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/categories?post=1851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.maj.aventure-pyreneenne.com\/index.php\/wp-json\/wp\/v2\/tags?post=1851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}